{"id":18517,"date":"2025-03-27T10:23:57","date_gmt":"2025-03-27T10:23:57","guid":{"rendered":"https:\/\/universal-gourmet-events.ch\/?post_type=cpt_services&#038;p=18517"},"modified":"2025-08-05T20:54:03","modified_gmt":"2025-08-05T20:54:03","slug":"chef-a-domicile-jura","status":"publish","type":"cpt_services","link":"https:\/\/universal-gourmet-events.ch\/fr\/services\/chef-zu-hause-in-basel\/","title":{"rendered":"Chef a domicile dans le Jura"},"content":{"rendered":"<h2 class=\"wp-block-heading\">Un chef chez vous<\/h2>\n\n\n\n<p>Nous nous d\u00e9pla\u00e7ons pour vous offrir une exp\u00e9rience unique, dans le confort de votre univers, dans le Jura et aux alentours.<\/p>\n\n\n\n<p>Et si votre cuisine devenait, le temps d\u2019un instant, une v\u00e9ritable sc\u00e8ne culinaire, pour vous faire voyager sans quitter votre maison ?<\/p>\n\n\n\n<p>Avec notre service \u00ab Chef \u00e0 domicile dans le Jura \u00bb, nous transformons votre cuisine en une exp\u00e9rience sur mesure, conviviale, raffin\u00e9e et sans stress.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04f55794fbd&quot;}\" data-wp-interactive=\"core\/image\" class=\"wp-block-image size-full wp-lightbox-container\"><img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"500\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on-async--click=\"actions.showLightbox\" data-wp-on-async--load=\"callbacks.setButtonStyles\" data-wp-on-async-window--resize=\"callbacks.setButtonStyles\" data-id=\"19217\" src=\"https:\/\/universal-gourmet-events.ch\/wp-content\/uploads\/2025\/03\/Kochdienste-zu-Hause-traiteur-basel-jura-universal-gourmet-events_675848970_XL.webp\" alt=\"Chef a domicile dans le Jura et a Bale\" class=\"wp-image-19217\" srcset=\"https:\/\/universal-gourmet-events.ch\/wp-content\/uploads\/2025\/03\/Kochdienste-zu-Hause-traiteur-basel-jura-universal-gourmet-events_675848970_XL.webp 800w, https:\/\/universal-gourmet-events.ch\/wp-content\/uploads\/2025\/03\/Kochdienste-zu-Hause-traiteur-basel-jura-universal-gourmet-events_675848970_XL-300x188.webp 300w, https:\/\/universal-gourmet-events.ch\/wp-content\/uploads\/2025\/03\/Kochdienste-zu-Hause-traiteur-basel-jura-universal-gourmet-events_675848970_XL-768x480.webp 768w, https:\/\/universal-gourmet-events.ch\/wp-content\/uploads\/2025\/03\/Kochdienste-zu-Hause-traiteur-basel-jura-universal-gourmet-events_675848970_XL-18x12.webp 18w, https:\/\/universal-gourmet-events.ch\/wp-content\/uploads\/2025\/03\/Kochdienste-zu-Hause-traiteur-basel-jura-universal-gourmet-events_675848970_XL-370x231.webp 370w, https:\/\/universal-gourmet-events.ch\/wp-content\/uploads\/2025\/03\/Kochdienste-zu-Hause-traiteur-basel-jura-universal-gourmet-events_675848970_XL-410x256.webp 410w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandir\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on-async--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04f5579535d&quot;}\" data-wp-interactive=\"core\/image\" class=\"wp-block-image size-full wp-lightbox-container\"><img decoding=\"async\" width=\"800\" height=\"533\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on-async--click=\"actions.showLightbox\" data-wp-on-async--load=\"callbacks.setButtonStyles\" data-wp-on-async-window--resize=\"callbacks.setButtonStyles\" data-id=\"19463\" src=\"https:\/\/universal-gourmet-events.ch\/wp-content\/uploads\/2025\/03\/Depositphotos_53781691_L.webp\" alt=\"\" class=\"wp-image-19463\" srcset=\"https:\/\/universal-gourmet-events.ch\/wp-content\/uploads\/2025\/03\/Depositphotos_53781691_L.webp 800w, https:\/\/universal-gourmet-events.ch\/wp-content\/uploads\/2025\/03\/Depositphotos_53781691_L-300x200.webp 300w, https:\/\/universal-gourmet-events.ch\/wp-content\/uploads\/2025\/03\/Depositphotos_53781691_L-768x512.webp 768w, https:\/\/universal-gourmet-events.ch\/wp-content\/uploads\/2025\/03\/Depositphotos_53781691_L-18x12.webp 18w, https:\/\/universal-gourmet-events.ch\/wp-content\/uploads\/2025\/03\/Depositphotos_53781691_L-370x247.webp 370w, https:\/\/universal-gourmet-events.ch\/wp-content\/uploads\/2025\/03\/Depositphotos_53781691_L-410x273.webp 410w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandir\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on-async--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04f5579566e&quot;}\" data-wp-interactive=\"core\/image\" class=\"wp-block-image size-large wp-lightbox-container\"><img decoding=\"async\" width=\"800\" height=\"533\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on-async--click=\"actions.showLightbox\" data-wp-on-async--load=\"callbacks.setButtonStyles\" data-wp-on-async-window--resize=\"callbacks.setButtonStyles\" data-id=\"19462\" src=\"https:\/\/universal-gourmet-events.ch\/wp-content\/uploads\/2025\/03\/Depositphotos_236582598_S.webp\" alt=\"\" class=\"wp-image-19462\" srcset=\"https:\/\/universal-gourmet-events.ch\/wp-content\/uploads\/2025\/03\/Depositphotos_236582598_S.webp 800w, https:\/\/universal-gourmet-events.ch\/wp-content\/uploads\/2025\/03\/Depositphotos_236582598_S-300x200.webp 300w, https:\/\/universal-gourmet-events.ch\/wp-content\/uploads\/2025\/03\/Depositphotos_236582598_S-768x512.webp 768w, https:\/\/universal-gourmet-events.ch\/wp-content\/uploads\/2025\/03\/Depositphotos_236582598_S-18x12.webp 18w, https:\/\/universal-gourmet-events.ch\/wp-content\/uploads\/2025\/03\/Depositphotos_236582598_S-370x247.webp 370w, https:\/\/universal-gourmet-events.ch\/wp-content\/uploads\/2025\/03\/Depositphotos_236582598_S-410x273.webp 410w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandir\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on-async--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/figure>\n\n\n\n<p>Que ce soit pour un d\u00eener, un anniversaire, un repas de famille ou un \u00e9v\u00e9nement priv\u00e9, notre cuisinier vient directement chez vous et pr\u00e9pare tout dans votre espace de confort. Notre service exclusif de cuisinier priv\u00e9 dans le Jura est synonyme d'une cuisine pleine de personnalit\u00e9, de pr\u00e9cision et de d\u00e9vouement.<\/p>\n\n\n\n<p>Notre offre :<br>\u2022 Un menu personnalis\u00e9, adapt\u00e9 \u00e0 vos envies<br>\u2022 Des options Halal, v\u00e9ganes, sans allerg\u00e8nes, sans MSG, ou simplement d\u2019inspiration gastronomique<br>\u2022 Des recettes inspir\u00e9es des cuisines du monde, avec une fusion des saveurs \u00e9quilibr\u00e9e<br>\u2022 Des produits frais, soigneusement s\u00e9lectionn\u00e9s dans la r\u00e9gion, selon des crit\u00e8res de qualit\u00e9 stricts<\/p>\n\n\n\n<p>Nous venons chez vous avec tous les ingr\u00e9dients, le mat\u00e9riel n\u00e9cessaire si besoin, une belle \u00e9nergie et la chaleur d\u2019une cuisine partag\u00e9e dans la bonne humeur.<\/p>\n\n\n\n<p>Prenez contact avec nous et cr\u00e9ons ensemble une parenth\u00e8se gourmande, intime et joyeuse, directement chez vous.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Laissez-vous porter sur le plan culinaire - avec votre chef a domicile dans le Jura<\/h3>\n\n\n\n<p>Vous pouvez prendre contact en cliquant <a href=\"https:\/\/universal-gourmet-events.ch\/fr\/contact\/\" data-type=\"page\" data-id=\"1453\">ici<\/a> , tout simplement.<\/p>","protected":false},"excerpt":{"rendered":"<p>Gourmetmomente in den eigenen vier W\u00e4nden<\/p>","protected":false},"author":1,"featured_media":19904,"comment_status":"open","ping_status":"closed","template":"","cpt_services_group":[178],"class_list":["post-18517","cpt_services","type-cpt_services","status-publish","has-post-thumbnail","hentry","cpt_services_group-catering-fur-private-anlasse-in-basel"],"_links":{"self":[{"href":"https:\/\/universal-gourmet-events.ch\/fr\/wp-json\/wp\/v2\/cpt_services\/18517","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/universal-gourmet-events.ch\/fr\/wp-json\/wp\/v2\/cpt_services"}],"about":[{"href":"https:\/\/universal-gourmet-events.ch\/fr\/wp-json\/wp\/v2\/types\/cpt_services"}],"author":[{"embeddable":true,"href":"https:\/\/universal-gourmet-events.ch\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/universal-gourmet-events.ch\/fr\/wp-json\/wp\/v2\/comments?post=18517"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/universal-gourmet-events.ch\/fr\/wp-json\/wp\/v2\/media\/19904"}],"wp:attachment":[{"href":"https:\/\/universal-gourmet-events.ch\/fr\/wp-json\/wp\/v2\/media?parent=18517"}],"wp:term":[{"taxonomy":"cpt_services_group","embeddable":true,"href":"https:\/\/universal-gourmet-events.ch\/fr\/wp-json\/wp\/v2\/cpt_services_group?post=18517"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}